{"id":45,"count":2,"description":"","link":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/","name":"Ole Plogstedt","slug":"ole-plogstedt","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ole Plogstedt Archive | Moderne-K\u00fcche Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ole Plogstedt Archive | Moderne-K\u00fcche Magazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/\" \/>\n<meta property=\"og:site_name\" content=\"Moderne-K\u00fcche Magazin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/\",\"url\":\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/\",\"name\":\"Ole Plogstedt Archive | Moderne-K\u00fcche Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.moderne-kueche.com\/magazin\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.moderne-kueche.com\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ole Plogstedt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.moderne-kueche.com\/magazin\/#website\",\"url\":\"https:\/\/www.moderne-kueche.com\/magazin\/\",\"name\":\"Moderne-K\u00fcche Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.moderne-kueche.com\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ole Plogstedt Archive | Moderne-K\u00fcche Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/","og_locale":"de_DE","og_type":"article","og_title":"Ole Plogstedt Archive | Moderne-K\u00fcche Magazin","og_url":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/","og_site_name":"Moderne-K\u00fcche Magazin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/","url":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/","name":"Ole Plogstedt Archive | Moderne-K\u00fcche Magazin","isPartOf":{"@id":"https:\/\/www.moderne-kueche.com\/magazin\/#website"},"breadcrumb":{"@id":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moderne-kueche.com\/magazin\/tag\/ole-plogstedt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.moderne-kueche.com\/magazin\/"},{"@type":"ListItem","position":2,"name":"Ole Plogstedt"}]},{"@type":"WebSite","@id":"https:\/\/www.moderne-kueche.com\/magazin\/#website","url":"https:\/\/www.moderne-kueche.com\/magazin\/","name":"Moderne-K\u00fcche Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moderne-kueche.com\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.moderne-kueche.com\/magazin\/wp-json\/wp\/v2\/tags\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moderne-kueche.com\/magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.moderne-kueche.com\/magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.moderne-kueche.com\/magazin\/wp-json\/wp\/v2\/posts?tags=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}